{"id":60428,"date":"2024-06-12T09:57:47","date_gmt":"2024-06-12T09:57:47","guid":{"rendered":"https:\/\/drlab.unitn.it\/?page_id=60428"},"modified":"2024-07-15T11:22:43","modified_gmt":"2024-07-15T11:22:43","slug":"call-for-papers","status":"publish","type":"page","link":"https:\/\/drlab.unitn.it\/fr\/call-for-papers\/","title":{"rendered":"Appel \u00e0 contributions"},"content":{"rendered":"<div id=\"fws_6a984752884d2\"  data-column-margin=\"default\" data-midnight=\"light\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer using-image\" ><div class=\"row-bg viewport-desktop using-image no-cover\"  style=\"background-image: url(https:\/\/drlab.unitn.it\/wp-content\/uploads\/2024\/02\/pointer.webp); background-position: left top; background-repeat: repeat; \"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: linear-gradient(to bottom,rgba(255,255,255,0.001) 25%,#ffffff 100%);  opacity: 1; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 light left\">\n\t<div style=\"\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col bg_img_front bl_br_25px br_br_25px left_padding_desktop_25px left_padding_tablet_0px left_padding_phone_0px right_padding_desktop_25px right_padding_tablet_0px right_padding_phone_0px\" data-using-bg=\"true\" data-overlay-color=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#dc1941\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-bg-pos=\"center center\" data-bg-animation=\"none\" data-bg-overlay=\"true\"><div class=\"inner-wrap\"><div class=\"column-image-bg\" style=\" background-image: url('https:\/\/drlab.unitn.it\/wp-content\/uploads\/2024\/02\/pointer.webp'); \"><\/div><\/div><\/div><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #dc1941;\"><\/div><div class=\"column-overlay-layer\" style=\"background-color:transparent;  opacity: 0.5; \"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap height_tablet_100px height_phone_80px\" data-alignment=\"default\"><div style=\"height: 160px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a9847528a4b6\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row  row_position_absolute bottom_position_desktop_-20px left_position_desktop_0px translate_x_-50pct bottom_position_tablet_-20px bottom_position_phone_-20px\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" data-scroll-animation=\"true\" data-scroll-animation-movement=\"transform_x\" data-scroll-animation-mobile=\"true\" data-scroll-animation-intensity=\"-2.5\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar-scrolling-text font_size_150px font_size_mobile_130px custom_color\" data-style=\"default\" data-s-dir=\"rtl\" data-spacing=\"true\" data-outline-thickness=\"thin\" data-s-speed=\"slower\" data-overflow=\"visible\" ><div class=\"nectar-scrolling-text-inner\" data-persist-animation data-nectar-animate-settings=\"{&quot;animations&quot;:{&quot;desktop&quot;:{&quot;translateX&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;25%&quot;},&quot;translateY&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;0&quot;},&quot;scale&quot;:{&quot;start&quot;:&quot;1&quot;,&quot;end&quot;:&quot;1&quot;},&quot;opacity&quot;:{&quot;start&quot;:&quot;1&quot;,&quot;end&quot;:&quot;1&quot;},&quot;rotate&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;0&quot;}},&quot;tablet&quot;:{&quot;translateX&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;25%&quot;},&quot;translateY&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;0&quot;},&quot;scale&quot;:{&quot;start&quot;:&quot;1&quot;,&quot;end&quot;:&quot;1&quot;},&quot;opacity&quot;:{&quot;start&quot;:&quot;1&quot;,&quot;end&quot;:&quot;1&quot;},&quot;rotate&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;0&quot;}},&quot;phone&quot;:{&quot;translateX&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;25%&quot;},&quot;translateY&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;0&quot;},&quot;scale&quot;:{&quot;start&quot;:&quot;1&quot;,&quot;end&quot;:&quot;1&quot;},&quot;opacity&quot;:{&quot;start&quot;:&quot;1&quot;,&quot;end&quot;:&quot;1&quot;},&quot;rotate&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;0&quot;}}},&quot;offsets&quot;:{&quot;start&quot;:&quot;0&quot;,&quot;end&quot;:&quot;100&quot;},&quot;config&quot;:[]}\" data-advanced-animation=\"true\" style=\"color: rgba(255,255,255,0.18);\"><div class=\"nectar-scrolling-text-inner__text-chunk\">\n<h1>Appel \u00e0 contributions<\/h1>\n<\/div><div class=\"nectar-scrolling-text-inner__text-chunk\">\n<h1>Appel \u00e0 contributions<\/h1>\n<\/div><div class=\"nectar-scrolling-text-inner__text-chunk\">\n<h1>Appel \u00e0 contributions<\/h1>\n<\/div><div class=\"nectar-scrolling-text-inner__text-chunk\">\n<h1>Appel \u00e0 contributions<\/h1>\n<\/div><div class=\"nectar-scrolling-text-inner__text-chunk\">\n<h1>Appel \u00e0 contributions<\/h1>\n<\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div id=\"fws_6a9847528bf14\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row vc_row-o-equal-height vc_row-flex vc_row-o-content-bottom\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column no-extra-padding column_element_direction_desktop_horizontal column_element_direction_tablet_horizontal column_element_direction_phone_horizontal left_margin_15px left_margin_tablet_0px left_margin_phone_0px inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-padding=\"20px\" data-color=\"white\" style=\"\" >\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 30px; line-height: 30px; height: 30px; width: 30px;\" class=\"icon-arrows-slim-right\"><\/i><\/div>\n\t<\/div><div class=\"nectar-split-heading\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"letter-reveal-bottom\" data-animation-type=\"line-reveal-by-space\" data-animation-delay=\"500\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"true\" data-custom-font-size=\"false\" ><h4 style=\" color: #ffffff;\">Appel \u00e0 contributions<\/h4><\/div>\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a9847528d84a\"  data-column-margin=\"100px\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section  top_margin_5pct\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col padding-2-percent inherit_tablet inherit_phone\"  data-padding-pos=\"right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div id=\"fws_6a9847528e33f\" data-midnight=\"\" data-column-margin=\"none\" class=\"wpb_row vc_row-fluid vc_row inner_row  top_padding_tablet_8pct\"  style=\"padding-bottom: 10px; \"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column has-animation no-extra-padding inherit_tablet inherit_phone\"   data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"fade-in-from-bottom\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h5><em>\u2192 SOUMETTRE VOTRE R\u00c9SUM\u00c9<\/em><\/h5>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div><div class=\"nectar-split-heading  font_size_3vw font_line_height_1-1\" data-align=\"default\" data-m-align=\"inherit\" data-text-effect=\"default\" data-animation-type=\"default\" data-animation-delay=\"0\" data-animation-offset=\"\" data-m-rm-animation=\"\" data-stagger=\"\" data-custom-font-size=\"true\" style=\"font-size: 3vw; line-height: 3.3vw;\"><div class=\"heading-line\" style=\"max-width: 600px;\"> <div><h2>Participer \u00e0 la<\/h2> <\/div> <\/div><div class=\"heading-line\" style=\"max-width: 600px;\"> <div><h2>Appel \u00e0 contributions !<\/h2> <\/div> <\/div><\/div><div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 5vh;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a9847529008f\"  data-column-margin=\"100px\" data-midnight=\"dark\" data-bottom-percent=\"10%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: 0px; padding-bottom: calc(100vw * 0.10); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col padding-2-percent inherit_tablet inherit_phone\"  data-padding-pos=\"right\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f60438-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"60438\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/pages\/60428#wpcf7-f60438-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" enctype=\"multipart\/form-data\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/fr\/wp-json\/wp\/v2\/pages\/60428#wpcf7-f60438-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"60438\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.6\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f60438-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<h6><strong>01. INS\u00c9RER VOS R\u00c9F\u00c9RENCES :<\/strong>\n<\/h6>\n<p style=\" margin-top:20px;\"><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nom *\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-surname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nom de famille *\" value=\"\" type=\"text\" name=\"your-surname\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-project\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Saisir le nom du projet*\" value=\"\" type=\"text\" name=\"your-project\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail *\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<h6><strong>02. JOINDRE VOTRE CURRICULUM VITAE<\/strong>\n<\/h6>\n<p style=\"font-size:16px;\">CURRICULUM : Joindre un PDF (Max 10MB)<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"curriculum\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-file\" accept=\"image\/*,.txt,application\/pdf\" aria-invalid=\"false\" type=\"file\" name=\"curriculum\" \/><\/span>\n<\/p>\n<p style=\"display: inline;\"><span class=\"wpcf7-form-control-wrap\" data-name=\"acconsento\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"acconsento\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span>\n<\/p>\n<p style=\"font-size: 14px !important;margin-top: -25px;padding-left: 56px !important;padding-bottom: 2vh !important;\">J'accepte le traitement de mes donn\u00e9es personnelles par Design Research Lab - D\u00e9partement des sciences humaines et de la philosophie de l'Universit\u00e9 de Trente, tel que d\u00e9fini dans la notice d'information, conform\u00e9ment au nouveau r\u00e8glement de l'UE 2016\/679 (GDPR) et au d\u00e9cret l\u00e9gislatif n\u00b0 196\/2003.\n<\/p>\n<div style=\" margin-top:20px;\">\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Envoyer\" \/>\n\t<\/p>\n<\/div><input type='hidden' class='wpcf7-pum' value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}' \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"fr\"\/><\/form>\n<\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n\n\t<div  class=\"vc_col-sm-6 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h6><strong>03. LISTE DES PROJETS<\/strong><\/h6>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 20px;\" class=\"divider\"><\/div><\/div><div id=\"fws_6a98475297703\" data-midnight=\"\" data-column-margin=\"default\" class=\"wpb_row vc_row-fluid vc_row inner_row\"  style=\"\"><div class=\"row-bg-wrap\"> <div class=\"row-bg\" ><\/div> <\/div><div class=\"row_col_wrap_12_inner col span_12  left\">\n\t<div style=\"margin-bottom: 2vh; \" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col child_column padding-3-percent column_element_direction_desktop_horizontal inherit_tablet inherit_phone\"   data-border-radius=\"20px\" data-border-animation=\"\" data-border-animation-delay=\"\" data-border-width=\"1px\" data-border-style=\"solid\" data-border-color=\"#c6c6c6\" data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" style=\"border: 1px solid #c6c6c6;\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"nectar_icon_wrap\" data-style=\"default\" data-padding=\"20px\" data-color=\"extra-color-1\" style=\"margin-right: 25px; \" >\n\t\t<div class=\"nectar_icon\" ><i style=\"font-size: 80px; line-height: 80px; height: 80px; width: 80px;\" class=\"steadysets-icon-folder-check\"><\/i><\/div>\n\t<\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<h3>Vous trouverez ici une liste de nos projets.<\/h3>\n<p>En attendant, vous pouvez utiliser le formulaire pour une candidature spontan\u00e9e.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t<\/div> \n\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a98475298c36\"  data-br=\"custom\" data-br-applies=\"bg\" data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row  tl_br_25px tr_br_25px bottom_margin_0px\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div style=\"\" class=\"vc_col-sm-12 wpb_column column_container vc_column_container col centered-text padding-10-percent column_element_direction_desktop_horizontal force-desktop-text-align-center column_element_direction_tablet_horizontal force-tablet-text-align-center column_element_direction_phone_horizontal force-phone-text-align-center inherit_tablet inherit_phone bg_img_front tl_br_25px tr_br_25px\" data-using-bg=\"true\" data-padding-pos=\"all\" data-has-bg-color=\"true\" data-bg-color=\"#ededed\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" ><div class=\"column-image-bg-wrap column-bg-layer viewport-desktop\" data-bg-pos=\"center center\" data-bg-animation=\"none\" data-bg-overlay=\"false\"><div class=\"inner-wrap\"><div class=\"column-image-bg\" style=\" background-image: url('https:\/\/drlab.unitn.it\/wp-content\/uploads\/2024\/02\/pointer.webp'); \"><\/div><\/div><\/div><div class=\"column-bg-overlay-wrap column-bg-layer\" data-bg-animation=\"none\"><div class=\"column-bg-overlay\" style=\"opacity: 1; background-color: #ededed;\"><\/div><\/div>\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><strong>Page suivante :<\/strong><\/p>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"nectar-cta  hover_color_dc1941 text_hover_color_ffffff alignment_tablet_default alignment_phone_default display_tablet_inherit display_phone_inherit\" data-color=\"black\" data-using-bg=\"true\" data-style=\"see-through\" data-display=\"block\" data-alignment=\"left\" data-text-color=\"custom\" style=\"margin-left: 10px;\"><p style=\"color: #ffffff;\"> <span class=\"text\"> <\/span><span class=\"link_wrap\" style=\"padding-top: 15px; padding-right: 20px; padding-bottom: 15px; padding-left: 20px;\"><a  class=\"link_text\" role=\"button\" href=\"https:\/\/drlab.unitn.it\/fr\/\">Page d'accueil<span class=\"arrow\"><\/span><\/a><\/span><\/p><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"Call for papers Call for papers Call for papers Call for papers Call for papers Call for papers \u2192 INVIA IL TUO ABSTRACT Partecipa alla Call for papers! 01. INSERISCI...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-60428","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/drlab.unitn.it\/fr\/wp-json\/wp\/v2\/pages\/60428","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drlab.unitn.it\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drlab.unitn.it\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drlab.unitn.it\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drlab.unitn.it\/fr\/wp-json\/wp\/v2\/comments?post=60428"}],"version-history":[{"count":22,"href":"https:\/\/drlab.unitn.it\/fr\/wp-json\/wp\/v2\/pages\/60428\/revisions"}],"predecessor-version":[{"id":60553,"href":"https:\/\/drlab.unitn.it\/fr\/wp-json\/wp\/v2\/pages\/60428\/revisions\/60553"}],"wp:attachment":[{"href":"https:\/\/drlab.unitn.it\/fr\/wp-json\/wp\/v2\/media?parent=60428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}